{"id":2169,"date":"2017-08-22T16:57:52","date_gmt":"2017-08-22T16:57:52","guid":{"rendered":"https:\/\/www.lancopaints.com\/america-central\/?p=2169\/"},"modified":"2025-06-23T21:33:36","modified_gmt":"2025-06-23T21:33:36","slug":"siliconflex","status":"publish","type":"post","link":"https:\/\/www.lancopaints.com\/honduras\/es\/products\/selladores-masillas\/selladores-acrilicos\/siliconflex\/","title":{"rendered":"SiliconFlex"},"content":{"rendered":"<p>Lanco\u00ae SiliconFlex\u2122 es un sellador acr\u00edlico modificado con silic\u00f3n para sellar e impermeabilizar uniones permanentemente. Combina en un solo componente las ventajas de adhesi\u00f3n permanente y resistencia a los rayos UV de los acr\u00edlicos, con la flexibilidad y gran durabilidad de la silicona.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lanco\u00ae SiliconFlex\u2122 es un sellador acr\u00edlico modificado con silic\u00f3n para sellar e impermeabilizar uniones permanentemente. Combina en un solo componente las ventajas de adhesi\u00f3n permanente y resistencia a los rayos UV de los acr\u00edlicos, con la flexibilidad y gran durabilidad de la silicona.<\/p>\n","protected":false},"author":1,"featured_media":2172,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[61],"tags":[],"class_list":["post-2169","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-selladores-acrilicos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>SiliconFlex - Lanco - Honduras<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lancopaints.com\/honduras\/es\/products\/selladores-masillas\/selladores-acrilicos\/siliconflex\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SiliconFlex - Lanco - Honduras\" \/>\n<meta property=\"og:description\" content=\"Lanco\u00ae SiliconFlex\u2122 es un sellador acr\u00edlico modificado con silic\u00f3n para sellar e impermeabilizar uniones permanentemente. Combina en un solo componente las ventajas de adhesi\u00f3n permanente y resistencia a los rayos UV de los acr\u00edlicos, con la flexibilidad y gran durabilidad de la silicona.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lancopaints.com\/honduras\/es\/products\/selladores-masillas\/selladores-acrilicos\/siliconflex\/\" \/>\n<meta property=\"og:site_name\" content=\"Lanco - Honduras\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/lancocentroamerica\" \/>\n<meta property=\"article:published_time\" content=\"2017-08-22T16:57:52+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-23T21:33:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.lancopaints.com\/honduras\/wp-content\/uploads\/sites\/14\/2017\/08\/SiliconFlex-CC766.png\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.lancopaints.com\/honduras\/es\/products\/selladores-masillas\/selladores-acrilicos\/siliconflex\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.lancopaints.com\/honduras\/es\/products\/selladores-masillas\/selladores-acrilicos\/siliconflex\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\/\/www.lancopaints.com\/honduras\/es\/#\/schema\/person\/ef3caca2f1f3e4e68384f3f427c52df4\"},\"headline\":\"SiliconFlex\",\"datePublished\":\"2017-08-22T16:57:52+00:00\",\"dateModified\":\"2025-06-23T21:33:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.lancopaints.com\/honduras\/es\/products\/selladores-masillas\/selladores-acrilicos\/siliconflex\/\"},\"wordCount\":48,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.lancopaints.com\/honduras\/es\/#organization\"},\"articleSection\":[\"Selladores Acr\u00edlicos\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.lancopaints.com\/honduras\/es\/products\/selladores-masillas\/selladores-acrilicos\/siliconflex\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.lancopaints.com\/honduras\/es\/products\/selladores-masillas\/selladores-acrilicos\/siliconflex\/\",\"url\":\"https:\/\/www.lancopaints.com\/honduras\/es\/products\/selladores-masillas\/selladores-acrilicos\/siliconflex\/\",\"name\":\"SiliconFlex - Lanco - Honduras\",\"isPartOf\":{\"@id\":\"https:\/\/www.lancopaints.com\/honduras\/es\/#website\"},\"datePublished\":\"2017-08-22T16:57:52+00:00\",\"dateModified\":\"2025-06-23T21:33:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.lancopaints.com\/honduras\/es\/products\/selladores-masillas\/selladores-acrilicos\/siliconflex\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.lancopaints.com\/honduras\/es\/products\/selladores-masillas\/selladores-acrilicos\/siliconflex\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.lancopaints.com\/honduras\/es\/products\/selladores-masillas\/selladores-acrilicos\/siliconflex\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.lancopaints.com\/honduras\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"SiliconFlex\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.lancopaints.com\/honduras\/es\/#website\",\"url\":\"https:\/\/www.lancopaints.com\/honduras\/es\/\",\"name\":\"Lanco - Honduras\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.lancopaints.com\/honduras\/es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.lancopaints.com\/honduras\/es\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.lancopaints.com\/honduras\/es\/#organization\",\"name\":\"Lanco - Centroam\u00e9rica\",\"url\":\"https:\/\/www.lancopaints.com\/honduras\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.lancopaints.com\/honduras\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.lancopaints.com\/america-central\/wp-content\/uploads\/sites\/14\/2017\/07\/lanco_logo.png\",\"contentUrl\":\"https:\/\/www.lancopaints.com\/america-central\/wp-content\/uploads\/sites\/14\/2017\/07\/lanco_logo.png\",\"width\":400,\"height\":221,\"caption\":\"Lanco - Centroam\u00e9rica\"},\"image\":{\"@id\":\"https:\/\/www.lancopaints.com\/honduras\/es\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/lancocentroamerica\",\"https:\/\/www.instagram.com\/lancocentroamerica\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.lancopaints.com\/honduras\/es\/#\/schema\/person\/ef3caca2f1f3e4e68384f3f427c52df4\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.lancopaints.com\/honduras\/es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/d69121ddf38e8dd3956dd5db2331999fde6388888c05965649931111c907a65b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/d69121ddf38e8dd3956dd5db2331999fde6388888c05965649931111c907a65b?s=96&d=mm&r=g\",\"caption\":\"admin\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"SiliconFlex - Lanco - Honduras","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lancopaints.com\/honduras\/es\/products\/selladores-masillas\/selladores-acrilicos\/siliconflex\/","og_locale":"es_ES","og_type":"article","og_title":"SiliconFlex - Lanco - Honduras","og_description":"Lanco\u00ae SiliconFlex\u2122 es un sellador acr\u00edlico modificado con silic\u00f3n para sellar e impermeabilizar uniones permanentemente. Combina en un solo componente las ventajas de adhesi\u00f3n permanente y resistencia a los rayos UV de los acr\u00edlicos, con la flexibilidad y gran durabilidad de la silicona.","og_url":"https:\/\/www.lancopaints.com\/honduras\/es\/products\/selladores-masillas\/selladores-acrilicos\/siliconflex\/","og_site_name":"Lanco - Honduras","article_publisher":"https:\/\/www.facebook.com\/lancocentroamerica","article_published_time":"2017-08-22T16:57:52+00:00","article_modified_time":"2025-06-23T21:33:36+00:00","og_image":[{"width":500,"height":500,"url":"https:\/\/www.lancopaints.com\/honduras\/wp-content\/uploads\/sites\/14\/2017\/08\/SiliconFlex-CC766.png","type":"image\/png"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.lancopaints.com\/honduras\/es\/products\/selladores-masillas\/selladores-acrilicos\/siliconflex\/#article","isPartOf":{"@id":"https:\/\/www.lancopaints.com\/honduras\/es\/products\/selladores-masillas\/selladores-acrilicos\/siliconflex\/"},"author":{"name":"admin","@id":"https:\/\/www.lancopaints.com\/honduras\/es\/#\/schema\/person\/ef3caca2f1f3e4e68384f3f427c52df4"},"headline":"SiliconFlex","datePublished":"2017-08-22T16:57:52+00:00","dateModified":"2025-06-23T21:33:36+00:00","mainEntityOfPage":{"@id":"https:\/\/www.lancopaints.com\/honduras\/es\/products\/selladores-masillas\/selladores-acrilicos\/siliconflex\/"},"wordCount":48,"commentCount":0,"publisher":{"@id":"https:\/\/www.lancopaints.com\/honduras\/es\/#organization"},"articleSection":["Selladores Acr\u00edlicos"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.lancopaints.com\/honduras\/es\/products\/selladores-masillas\/selladores-acrilicos\/siliconflex\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.lancopaints.com\/honduras\/es\/products\/selladores-masillas\/selladores-acrilicos\/siliconflex\/","url":"https:\/\/www.lancopaints.com\/honduras\/es\/products\/selladores-masillas\/selladores-acrilicos\/siliconflex\/","name":"SiliconFlex - Lanco - Honduras","isPartOf":{"@id":"https:\/\/www.lancopaints.com\/honduras\/es\/#website"},"datePublished":"2017-08-22T16:57:52+00:00","dateModified":"2025-06-23T21:33:36+00:00","breadcrumb":{"@id":"https:\/\/www.lancopaints.com\/honduras\/es\/products\/selladores-masillas\/selladores-acrilicos\/siliconflex\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lancopaints.com\/honduras\/es\/products\/selladores-masillas\/selladores-acrilicos\/siliconflex\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.lancopaints.com\/honduras\/es\/products\/selladores-masillas\/selladores-acrilicos\/siliconflex\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.lancopaints.com\/honduras\/es\/"},{"@type":"ListItem","position":2,"name":"SiliconFlex"}]},{"@type":"WebSite","@id":"https:\/\/www.lancopaints.com\/honduras\/es\/#website","url":"https:\/\/www.lancopaints.com\/honduras\/es\/","name":"Lanco - Honduras","description":"","publisher":{"@id":"https:\/\/www.lancopaints.com\/honduras\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lancopaints.com\/honduras\/es\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.lancopaints.com\/honduras\/es\/#organization","name":"Lanco - Centroam\u00e9rica","url":"https:\/\/www.lancopaints.com\/honduras\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.lancopaints.com\/honduras\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.lancopaints.com\/america-central\/wp-content\/uploads\/sites\/14\/2017\/07\/lanco_logo.png","contentUrl":"https:\/\/www.lancopaints.com\/america-central\/wp-content\/uploads\/sites\/14\/2017\/07\/lanco_logo.png","width":400,"height":221,"caption":"Lanco - Centroam\u00e9rica"},"image":{"@id":"https:\/\/www.lancopaints.com\/honduras\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/lancocentroamerica","https:\/\/www.instagram.com\/lancocentroamerica\/"]},{"@type":"Person","@id":"https:\/\/www.lancopaints.com\/honduras\/es\/#\/schema\/person\/ef3caca2f1f3e4e68384f3f427c52df4","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.lancopaints.com\/honduras\/es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/d69121ddf38e8dd3956dd5db2331999fde6388888c05965649931111c907a65b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d69121ddf38e8dd3956dd5db2331999fde6388888c05965649931111c907a65b?s=96&d=mm&r=g","caption":"admin"}}]}},"_links":{"self":[{"href":"https:\/\/www.lancopaints.com\/honduras\/es\/wp-json\/wp\/v2\/posts\/2169\/"}],"collection":[{"href":"https:\/\/www.lancopaints.com\/honduras\/es\/wp-json\/wp\/v2\/posts\/"}],"about":[{"href":"https:\/\/www.lancopaints.com\/honduras\/es\/wp-json\/wp\/v2\/types\/post\/"}],"author":[{"embeddable":true,"href":"https:\/\/www.lancopaints.com\/honduras\/es\/wp-json\/wp\/v2\/users\/1\/"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lancopaints.com\/honduras\/es\/wp-json\/wp\/v2\/comments\/?post=2169"}],"version-history":[{"count":0,"href":"https:\/\/www.lancopaints.com\/honduras\/es\/wp-json\/wp\/v2\/posts\/2169\/revisions\/"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lancopaints.com\/honduras\/es\/wp-json\/wp\/v2\/media\/2172\/"}],"wp:attachment":[{"href":"https:\/\/www.lancopaints.com\/honduras\/es\/wp-json\/wp\/v2\/media\/?parent=2169"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lancopaints.com\/honduras\/es\/wp-json\/wp\/v2\/categories\/?post=2169"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lancopaints.com\/honduras\/es\/wp-json\/wp\/v2\/tags\/?post=2169"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}